{"id":657,"date":"2025-05-22T01:03:41","date_gmt":"2025-05-22T04:03:41","guid":{"rendered":"https:\/\/holfik.com\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/"},"modified":"2025-05-22T01:03:41","modified_gmt":"2025-05-22T04:03:41","slug":"flamengo-avanca-com-vitoria-sobre-botafogo-pb","status":"publish","type":"post","link":"https:\/\/holfik.com\/fr\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/","title":{"rendered":"Flamengo avance avec la victoire sur Botafogo-PB"},"content":{"rendered":"<p><img style='width: 100%; height: auto;' src='http:\/\/holfik.com\/wp-content\/uploads\/2025\/05\/file-56.jpg' alt='imagem do artigo'\/><\/p>\n<p><strong>Flamengo progresse<\/strong> en Coupe du Br\u00e9sil apr\u00e8s une impressionnante victoire contre Botafogo-PB lors du match retour de la Troisi\u00e8me Phase, disput\u00e9 au Maracan\u00e3.<\/p>\n<p><div class=\"animated-button animated-border\" data-type=\"2\"><a href=\"https:\/\/holfik.com\/fr\/flamengo-se-prepara-para-enfrentar-botafogo-pb\/\" class=\"btn-base\"><div class=\"img-area\"><img decoding=\"async\" class=\"second-level-img\" alt=\"\" src=\"http:\/\/holfik.com\/wp-content\/uploads\/2025\/05\/file-55.jpg\"><\/div><div class=\"infos-area\"><div class=\"second-level-info\">FLAMENGO EST PR\u00caT \u00c0 RELEVER LE D\u00c9FI CONTRE BOTAFOGO-PB<\/div><div class=\"second-level-title\">Les pr\u00e9paratifs de Flamengo<\/div><div class=\"second-level-description\">D\u00e9couvrez comment Flamengo se pr\u00e9pare \u00e0 affronter l&#039;\u00e9quipe de Para\u00edba dans un autre d\u00e9fi de la Copa do Brasil !<\/div><div class=\"second-level-cta\">Flamengo se pr\u00e9pare \u00e0 affronter Botafogo-PB<\/div><\/div><\/a><\/div><\/p>\n<p>Flamengo, qui a montr\u00e9 un contr\u00f4le absolu de la possession et une performance intense, a marqu\u00e9 quatre buts, les plus marquants \u00e9tant Danilo, Pedro, Varela et Cebolinha.<\/p>\n<p>Dans cet article, nous explorerons les principaux moments du match, les strat\u00e9gies utilis\u00e9es par Meng\u00e3o et la r\u00e9action de Botafogo-PB, qui, malgr\u00e9 la d\u00e9faite, a r\u00e9ussi \u00e0 marquer deux buts.<\/p>\n<p>La performance de l&#039;\u00e9quipe de Rio de Janeiro a \u00e9t\u00e9 d\u00e9cisive pour garantir la qualification pour les huiti\u00e8mes de finale de la comp\u00e9tition.<\/p>\n<h2>Flamengo se qualifie pour les huiti\u00e8mes de finale gr\u00e2ce \u00e0 sa victoire contre Botafogo-PB<\/h2>\n<p><p>Dans le <strong>Mercredi 21<\/strong>, le <strong>flamand<\/strong> ont assur\u00e9 leur qualification pour les huiti\u00e8mes de finale de la Copa do Brasil en battant <strong>Botafogo-PB<\/strong> par 4 \u00d7 2 dans un match d\u00e9cisif \u00e0 l&#039;embl\u00e9matique <strong>Maracan\u00e3<\/strong>.<\/p>\n<p>Le duel a marqu\u00e9 le match retour de la troisi\u00e8me phase de la comp\u00e9tition et a r\u00e9v\u00e9l\u00e9 une \u00e9quipe Rubro-Negro dominante d\u00e8s le coup de sifflet d&#039;ouverture, m\u00eame avec une composition mixte et un public plus petit que d&#039;habitude.<\/p>\n<\/p>\n<p>Sur le terrain, l&#039;\u00e9quipe dirig\u00e9e par Filipe Lu\u00eds a contr\u00f4l\u00e9 la possession du ballon, a montr\u00e9 de l&#039;intensit\u00e9 dans ses jeux et n&#039;a donn\u00e9 aucune chance \u00e0 l&#039;\u00e9quipe de Para\u00edba en premi\u00e8re mi-temps.<\/p>\n<p>Avec les buts de Danilo, Pedro, Varela et Cebolinha, le <strong>flamand<\/strong> ils ont construit une avance solide avant la mi-temps, ce qui leur a permis de g\u00e9rer le r\u00e9sultat sans aucune frayeur.<\/p>\n<p>D\u00e9j\u00e0 le <strong>Botafogo-PB<\/strong> a r\u00e9agi avec deux buts, mais n&#039;a pas r\u00e9ussi \u00e0 menacer le classement de Rio de Janeiro.<\/p>\n<p>Avec cette victoire, Meng\u00e3o confirme sa force \u00e0 domicile et reste ferme dans la recherche du titre national.<\/p>\n<\/p>\n<h2>But de Varela \u00e0 la 21e minute<\/h2>\n<p>Au <u><strong>21 minutes apr\u00e8s le d\u00e9but de la premi\u00e8re mi-temps<\/strong><\/u>, un mouvement brillant entre deux joueurs de Flamengo a abouti au troisi\u00e8me but de l&#039;\u00e9quipe.<\/p>\n<p>De gauche \u00e0 droite, <u><strong>Ayrton Lucas<\/strong><\/u> Il a avanc\u00e9 avec vitesse et pr\u00e9cision, trouvant l&#039;espace pour lever la t\u00eate et faire un centre millim\u00e9trique dans la surface.<\/p>\n<p>Le ballon a travers\u00e9 la d\u00e9fense de Botafogo-PB et a trouv\u00e9 <u><strong>Varela<\/strong><\/u>, qui arrivait de derri\u00e8re \u00e0 grande vitesse.<\/p>\n<p>L&#039;arri\u00e8re droit a fait preuve de pr\u00e9cision et de sang-froid en d\u00e9cochant un tir crois\u00e9 imparable pour le gardien adverse.<\/p>\n<p>Ce moment d&#039;harmonie offensive a mis en \u00e9vidence la domination de Flamengo dans le match, augmentant l&#039;avantage en <a href=\"https:\/\/www.uol.com.br\/esporte\/futebol\/ultimas-noticias\/2025\/05\/21\/flamengo-x-botafogo-pb-pela-copa-do-brasil.htm\" alt=\"Jogo Flamengo x Botafogo-PB pela Copa do Brasil\">duel d\u00e9cisif contre Botafogo-PB pour la Copa do Brasil<\/a>.<\/p>\n<h2>Coup de t\u00eate de Cebolinha au d\u00e9but de la seconde mi-temps<\/h2>\n<p>Juste apr\u00e8s la pause, le <u><strong>flamand<\/strong><\/u> est revenu avec intensit\u00e9 et a surpris Botafogo-PB d\u00e9fensivement.<\/p>\n<p>Dans une action organis\u00e9e sur le c\u00f4t\u00e9 droit, Varela a invers\u00e9 son r\u00f4le habituel de finisseur et a assum\u00e9 le r\u00f4le principal dans la mise en place.<\/p>\n<p>Alors qu&#039;il avan\u00e7ait sur l&#039;aile, il contr\u00f4lait le ballon avec pr\u00e9cision et ex\u00e9cutait un <u>croisement millim\u00e9trique<\/u> qui a trouv\u00e9 <u><strong>Oignon vert<\/strong><\/u> parfaitement positionn\u00e9 dans le quartier.<\/p>\n<p>L&#039;attaquant s&#039;est lev\u00e9 au bon moment et, d&#039;une t\u00eate ferme, a mis le ballon au fond des filets, marquant le <strong>quatri\u00e8me but rouge-noir<\/strong>.<\/p>\n<p>Comme le souligne l\u2019analyse de la <a href=\"https:\/\/www.tupi.fm\/esportes\/flamengo-x-botafogo-pb-jogo-de-volta-da-3a-fase-da-copa-do-brasil\/\" alt=\"Resumo da vit\u00f3ria do Flamengo sobre o Botafogo-PB\">Site Web de Tupi FM<\/a>, le jeu a consolid\u00e9 la domination de l&#039;\u00e9quipe de Rio de Janeiro au d\u00e9but de la seconde mi-temps.<\/p>\n<h2>But d&#039;Henrique Dourado \u00e0 la 35&#039;<\/h2>\n<p>M\u00eame sous la forte pression de Flamengo et avec un score en d\u00e9savantage, Botafogo-PB a r\u00e9ussi \u00e0 r\u00e9duire l&#039;\u00e9cart en premi\u00e8re mi-temps.<\/p>\n<p>Au <strong>35 minutes<\/strong>, dans une rare \u00e9chapp\u00e9e offensive, Henrique Dourado a profit\u00e9 d&#039;une erreur de positionnement de la d\u00e9fense rouge-noir et ne l&#039;a pas g\u00e2ch\u00e9e : il a contr\u00f4l\u00e9 le ballon avec classe et a termin\u00e9 en travers, battant le gardien.<\/p>\n<p>L&#039;objectif de la <strong>Henri Golden<\/strong>, \u00e9galement connu sous le nom de Ceifador, ancien attaquant de Flamengo, s&#039;est distingu\u00e9 non seulement par son poids symbolique \u2014 le fameux \u00ab ex-loi \u00bb \u2014 mais aussi par son ex\u00e9cution technique, qui a montr\u00e9 l&#039;opportunisme de l&#039;avant-centre de Belo en <u>Maracan\u00e3<\/u>.<\/p>\n<h2>Deuxi\u00e8me but de Rodrigo Alves \u00e0 la 29e minute de la seconde p\u00e9riode<\/h2>\n<blockquote><p>Le but qui a r\u00e9duit l&#039;avantage de Flamengo est survenu apr\u00e8s un corner venu de la droite.<\/p>\n<\/blockquote>\n<p> Au <strong>29 minutes<\/strong> en deuxi\u00e8me mi-temps, la d\u00e9fense rouge et noire a partiellement d\u00e9gag\u00e9 le centre, mais le ballon a \u00e9t\u00e9 laiss\u00e9 propre au bord de la surface pour <strong>Rodrigo Alves<\/strong>.<\/p>\n<p>Sans r\u00e9fl\u00e9chir \u00e0 deux fois, le joueur a ajout\u00e9 un <u>coup de pied puissant<\/u> premi\u00e8re fois, en frappant le coin gauche du gardien avec pr\u00e9cision.<\/p>\n<p>Ce magnifique but a provoqu\u00e9 une r\u00e9action dans les tribunes et a mis la pression sur l&#039;\u00e9quipe locale pendant quelques minutes.<\/p>\n<p>Le mouvement du num\u00e9ro 23 de Botafogo-PB a \u00e9t\u00e9 fondamental pour profiter du rebond, mettant en valeur sa lecture rapide du jeu et sa capacit\u00e9 \u00e0 terminer \u00e0 moyenne distance.<\/p>\n<h2>Gestion de la possession et du contr\u00f4le dans les derni\u00e8res minutes<\/h2>\n<p>Dans les derni\u00e8res minutes du match contre Botafogo-PB pour la Copa do Brasil, Flamengo a d\u00e9montr\u00e9 un contr\u00f4le strat\u00e9gique remarquable dans la gestion du <strong>possession du ballon<\/strong> avec intelligence et pr\u00e9cision.<\/p>\n<p>Avec une avance confortable au tableau d&#039;affichage, l&#039;\u00e9quipe a adopt\u00e9 une position prudente, \u00e9vitant de s&#039;exposer inutilement et emp\u00eachant l&#039;adversaire de grandir dans le jeu.<\/p>\n<p>Au lieu de chercher la d\u00e9route, les joueurs ont commenc\u00e9 \u00e0 valoriser chaque jeu, d\u00e9montrant une maturit\u00e9 tactique dans la conduite du jeu. <strong>rythme du jeu<\/strong>.<\/p>\n<p>Cette approche a servi \u00e0 refroidir la r\u00e9action de Botafogo-PB, qui cherchait toujours un \u00e9ventuel retour.<\/p>\n<p>Profitant de leur sup\u00e9riorit\u00e9 technique, l&#039;\u00e9quipe a gard\u00e9 le ballon loin de sa zone d\u00e9fensive, devenant ainsi propri\u00e9taire absolue des actions sur le terrain.<\/p>\n<p>Cette domination peut \u00eatre observ\u00e9e \u00e0 travers quelques actions tactiques essentielles :<\/p>\n<ul>\n<li><u>\u00c9change constant de passes courtes<\/u>, ce qui rend difficile le marquage pour l&#039;adversaire<\/li>\n<li>Utiliser les arri\u00e8res lat\u00e9raux pour \u00e9largir le terrain et cr\u00e9er de l&#039;espace<\/li>\n<li><strong>recul contr\u00f4l\u00e9<\/strong> depuis la ligne d&#039;attaque pour compacter l&#039;\u00e9quipe et r\u00e9duire les options du rival<\/li>\n<\/ul>\n<p>Ce contr\u00f4le a permis \u00e0 Flamengo de se qualifier en toute s\u00e9curit\u00e9, en conservant l&#039;avantage sans prendre de risques inutiles. <a href=\"https:\/\/ge.globo.com\/rj\/futebol\/copa-do-brasil\/jogo\/21-05-2025\/flamengo-botafogo-pb.ghtml\" alt=\"Veja como foi Flamengo x Botafogo-PB pela Copa do Brasil\">comme enregistr\u00e9 dans la couverture de GE<\/a>.<\/p>\n<p><strong>Flamengo progresse<\/strong> avec cette victoire, il se consolide comme un concurrent s\u00e9rieux dans la Copa do Brasil.<\/p>\n<p>L&#039;\u00e9quipe a fait preuve d&#039;habilet\u00e9 et de contr\u00f4le tout au long du match, s&#039;assurant une place en huiti\u00e8mes de finale.<\/p>\n<div>\n<h4 style=\"text-align: center;\"><\/h4>\n<p> <a href=\"https:\/\/www.uol.com.br\/esporte\/futebol\/ultimas-noticias\/2025\/05\/21\/flamengo-x-botafogo-pb-pela-copa-do-brasil.htm\" class=\"btn-custom theme\">Flamengo x Botafogo PB pour la Coupe du Br\u00e9sil<\/a> <a href=\"https:\/\/www.tupi.fm\/esportes\/flamengo-x-botafogo-pb-jogo-de-volta-da-3a-fase-da-copa-do-brasil\/\" class=\"btn-custom theme-outline\">Flamengo x Botafogo PB Match retour de la 3e phase<\/a> <a href=\"https:\/\/ge.globo.com\/rj\/futebol\/copa-do-brasil\/jogo\/21-05-2025\/flamengo-botafogo-pb.ghtml\" class=\"btn-custom theme\">Flamengo Botafogo PB<\/a> <\/div>","protected":false},"excerpt":{"rendered":"<p>Flamengo avance en Coupe du Br\u00e9sil apr\u00e8s une impressionnante victoire contre Botafogo-PB lors du match retour de la troisi\u00e8me phase, disput\u00e9 au Maracan\u00e3. FLAMENGO EST PR\u00caT POUR LE D\u00c9FI CONTRE BOTAFOGO-PBLes pr\u00e9paratifs de FlamengoD\u00e9couvrez comment Flamengo se pr\u00e9pare \u00e0 affronter l&#039;\u00e9quipe de Para\u00edba dans un autre d\u00e9fi de la Copa do [\u2026]<\/p>","protected":false},"author":8,"featured_media":656,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[139],"tags":[160,159,140],"class_list":["post-657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-flamengo","tag-botafogo-pb","tag-copa-do-brasil","tag-flamengo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Flamengo Avan\u00e7a Com Vit\u00f3ria Sobre Botafogo-PB - Holfik<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/holfik.com\/fr\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Flamengo Avan\u00e7a Com Vit\u00f3ria Sobre Botafogo-PB - Holfik\" \/>\n<meta property=\"og:description\" content=\"Flamengo Avan\u00e7a na Copa do Brasil ap\u00f3s uma expressiva vit\u00f3ria sobre o Botafogo-PB no jogo de volta da Terceira Fase, realizado no Maracan\u00e3. FLAMENGO EST\u00e1 PRONTO PARA O DESAFIO CONTRA BOTAFOGO-PBPreparativos do FlamengoSaiba como o Flamengo se prepara para enfrentar a equipe paraibana em mais um desafio na Copa do [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/holfik.com\/fr\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/\" \/>\n<meta property=\"og:site_name\" content=\"Holfik\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-22T04:03:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/05\/req-pAfI8QNjobD3xvpOsw7bJ.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"624\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"MatheusTI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"MatheusTI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/\"},\"author\":{\"name\":\"MatheusTI\",\"@id\":\"https:\/\/holfik.com\/nb\/#\/schema\/person\/8439ae3f9f66b82e3e8a753089c94904\"},\"headline\":\"Flamengo Avan\u00e7a Com Vit\u00f3ria Sobre Botafogo-PB\",\"datePublished\":\"2025-05-22T04:03:41+00:00\",\"dateModified\":\"2025-05-22T04:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/\"},\"wordCount\":1007,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/holfik.com\/nb\/#organization\"},\"image\":{\"@id\":\"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/05\/req-pAfI8QNjobD3xvpOsw7bJ.png\",\"keywords\":[\"Botafogo-PB\",\"Copa do Brasil\",\"Flamengo\"],\"articleSection\":[\"Flamengo\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/\",\"url\":\"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/\",\"name\":\"Flamengo Avan\u00e7a Com Vit\u00f3ria Sobre Botafogo-PB - Holfik\",\"isPartOf\":{\"@id\":\"https:\/\/holfik.com\/nb\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/05\/req-pAfI8QNjobD3xvpOsw7bJ.png\",\"datePublished\":\"2025-05-22T04:03:41+00:00\",\"dateModified\":\"2025-05-22T04:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/#primaryimage\",\"url\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/05\/req-pAfI8QNjobD3xvpOsw7bJ.png\",\"contentUrl\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/05\/req-pAfI8QNjobD3xvpOsw7bJ.png\",\"width\":1024,\"height\":624,\"caption\":\"Flamengo celebra a vit\u00f3ria sobre o Botafogo-PB na Copa do Brasil.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/holfik.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Flamengo Avan\u00e7a Com Vit\u00f3ria Sobre Botafogo-PB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/holfik.com\/nb\/#website\",\"url\":\"https:\/\/holfik.com\/nb\/\",\"name\":\"Holfik\",\"description\":\"Site de Not\u00edcias e M\u00eddia\",\"publisher\":{\"@id\":\"https:\/\/holfik.com\/nb\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/holfik.com\/nb\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/holfik.com\/nb\/#organization\",\"name\":\"Holfik\",\"url\":\"https:\/\/holfik.com\/nb\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/holfik.com\/nb\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/download1.png\",\"contentUrl\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/download1.png\",\"width\":150,\"height\":100,\"caption\":\"Holfik\"},\"image\":{\"@id\":\"https:\/\/holfik.com\/nb\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/holfik.com\/nb\/#\/schema\/person\/8439ae3f9f66b82e3e8a753089c94904\",\"name\":\"MatheusTI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/holfik.com\/nb\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/47b026cb9cf612d1551ce28c18094d65bf8db31f996a5b0ab68921465dfa720e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/47b026cb9cf612d1551ce28c18094d65bf8db31f996a5b0ab68921465dfa720e?s=96&d=mm&r=g\",\"caption\":\"MatheusTI\"},\"url\":\"https:\/\/holfik.com\/fr\/author\/matheusti\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Flamengo Avan\u00e7a Com Vit\u00f3ria Sobre Botafogo-PB - Holfik","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/holfik.com\/fr\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/","og_locale":"fr_FR","og_type":"article","og_title":"Flamengo Avan\u00e7a Com Vit\u00f3ria Sobre Botafogo-PB - Holfik","og_description":"Flamengo Avan\u00e7a na Copa do Brasil ap\u00f3s uma expressiva vit\u00f3ria sobre o Botafogo-PB no jogo de volta da Terceira Fase, realizado no Maracan\u00e3. FLAMENGO EST\u00e1 PRONTO PARA O DESAFIO CONTRA BOTAFOGO-PBPreparativos do FlamengoSaiba como o Flamengo se prepara para enfrentar a equipe paraibana em mais um desafio na Copa do [&hellip;]","og_url":"https:\/\/holfik.com\/fr\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/","og_site_name":"Holfik","article_published_time":"2025-05-22T04:03:41+00:00","og_image":[{"width":1024,"height":624,"url":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/05\/req-pAfI8QNjobD3xvpOsw7bJ.png","type":"image\/png"}],"author":"MatheusTI","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"MatheusTI","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/#article","isPartOf":{"@id":"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/"},"author":{"name":"MatheusTI","@id":"https:\/\/holfik.com\/nb\/#\/schema\/person\/8439ae3f9f66b82e3e8a753089c94904"},"headline":"Flamengo Avan\u00e7a Com Vit\u00f3ria Sobre Botafogo-PB","datePublished":"2025-05-22T04:03:41+00:00","dateModified":"2025-05-22T04:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/"},"wordCount":1007,"commentCount":0,"publisher":{"@id":"https:\/\/holfik.com\/nb\/#organization"},"image":{"@id":"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/#primaryimage"},"thumbnailUrl":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/05\/req-pAfI8QNjobD3xvpOsw7bJ.png","keywords":["Botafogo-PB","Copa do Brasil","Flamengo"],"articleSection":["Flamengo"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/","url":"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/","name":"Flamengo Avan\u00e7a Com Vit\u00f3ria Sobre Botafogo-PB - Holfik","isPartOf":{"@id":"https:\/\/holfik.com\/nb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/#primaryimage"},"image":{"@id":"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/#primaryimage"},"thumbnailUrl":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/05\/req-pAfI8QNjobD3xvpOsw7bJ.png","datePublished":"2025-05-22T04:03:41+00:00","dateModified":"2025-05-22T04:03:41+00:00","breadcrumb":{"@id":"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/#primaryimage","url":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/05\/req-pAfI8QNjobD3xvpOsw7bJ.png","contentUrl":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/05\/req-pAfI8QNjobD3xvpOsw7bJ.png","width":1024,"height":624,"caption":"Flamengo celebra a vit\u00f3ria sobre o Botafogo-PB na Copa do Brasil."},{"@type":"BreadcrumbList","@id":"https:\/\/holfik.com\/it\/flamengo-avanca-com-vitoria-sobre-botafogo-pb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/holfik.com\/"},{"@type":"ListItem","position":2,"name":"Flamengo Avan\u00e7a Com Vit\u00f3ria Sobre Botafogo-PB"}]},{"@type":"WebSite","@id":"https:\/\/holfik.com\/nb\/#website","url":"https:\/\/holfik.com\/nb\/","name":"Holfik","description":"Site de Not\u00edcias e M\u00eddia","publisher":{"@id":"https:\/\/holfik.com\/nb\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/holfik.com\/nb\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/holfik.com\/nb\/#organization","name":"Holfik","url":"https:\/\/holfik.com\/nb\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/holfik.com\/nb\/#\/schema\/logo\/image\/","url":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/download1.png","contentUrl":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/download1.png","width":150,"height":100,"caption":"Holfik"},"image":{"@id":"https:\/\/holfik.com\/nb\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/holfik.com\/nb\/#\/schema\/person\/8439ae3f9f66b82e3e8a753089c94904","name":"MatheusTI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/holfik.com\/nb\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/47b026cb9cf612d1551ce28c18094d65bf8db31f996a5b0ab68921465dfa720e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/47b026cb9cf612d1551ce28c18094d65bf8db31f996a5b0ab68921465dfa720e?s=96&d=mm&r=g","caption":"MatheusTI"},"url":"https:\/\/holfik.com\/fr\/author\/matheusti\/"}]}},"_links":{"self":[{"href":"https:\/\/holfik.com\/fr\/wp-json\/wp\/v2\/posts\/657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/holfik.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/holfik.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/holfik.com\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/holfik.com\/fr\/wp-json\/wp\/v2\/comments?post=657"}],"version-history":[{"count":0,"href":"https:\/\/holfik.com\/fr\/wp-json\/wp\/v2\/posts\/657\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/holfik.com\/fr\/wp-json\/wp\/v2\/media\/656"}],"wp:attachment":[{"href":"https:\/\/holfik.com\/fr\/wp-json\/wp\/v2\/media?parent=657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/holfik.com\/fr\/wp-json\/wp\/v2\/categories?post=657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/holfik.com\/fr\/wp-json\/wp\/v2\/tags?post=657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}