{"id":1885,"date":"2025-12-07T17:02:02","date_gmt":"2025-12-07T20:02:02","guid":{"rendered":"https:\/\/holfik.com\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/"},"modified":"2025-12-07T17:02:02","modified_gmt":"2025-12-07T20:02:02","slug":"expectativa-de-nova-greve-dos-caminhoneiros-aumenta","status":"publish","type":"post","link":"https:\/\/holfik.com\/esp\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/","title":{"rendered":"Aumentan las expectativas de una nueva huelga de camioneros"},"content":{"rendered":"<p><strong>Huelga de camioneros<\/strong> Este es el tema central de este art\u00edculo, que explorar\u00e1 la creciente expectativa de una nueva huelga de camioneros en Brasil, especialmente despu\u00e9s de la reciente huelga nacional del 4 de diciembre.<\/p>\n<p>Analicemos c\u00f3mo impacta esta situaci\u00f3n en los precios de los combustibles, pudiendo la gasolina superar los R$ 10 por litro.<\/p>\n<p>Adem\u00e1s, abordaremos las razones detr\u00e1s de las protestas, que incluyen las malas condiciones de trabajo y el aumento del ICMS (impuesto brasile\u00f1o sobre las ventas).<\/p>\n<p>Tambi\u00e9n se abordar\u00e1 la divisi\u00f3n entre los camioneros, destacando las motivaciones pol\u00edticas y sus preocupaciones econ\u00f3micas.<\/p>\n<p>Por \u00faltimo, analizaremos las proyecciones econ\u00f3micas para el futuro del sector de transporte en Brasil.<\/p>\n<h2>Creciente tensi\u00f3n en el transporte por carretera<\/h2>\n<p>Hay grandes expectativas de una nueva huelga de camioneros en <u><strong>4 de diciembre<\/strong><\/u> Esto est\u00e1 causando gran preocupaci\u00f3n en todo Brasil.<\/p>\n<p>Los camioneros est\u00e1n listos para protestar nuevamente debido a <strong>condiciones de trabajo insostenibles<\/strong> y al continuo aumento de los precios de los combustibles.<\/p>\n<p>oh <strong>precio promedio de la gasolina<\/strong> actualmente alcanza <strong>R$ 6,38 por litro<\/strong>Sin embargo, algunas proyecciones indican que el valor podr\u00eda superar... <strong>R$ 10<\/strong> Si la huelga persiste, afectar\u00e1 gravemente la econom\u00eda nacional.<\/p>\n<p>La divisi\u00f3n interna entre los camioneros, con algunos grupos que se oponen a la huelga, a\u00f1ade m\u00e1s capas a la ya compleja situaci\u00f3n. [La amenaza de una nueva huelga podr\u00eda reavivar amargos recuerdos de 2018](https:\/\/clickpetroleoegas.com.br\/nova-ameaca-de-greve-dos-caminhoneiros-reacende-fantasma-de-2018-pode-empurrar-gasolina-acima-de-r-10-causar-desabastecimento-filas-e-alta-de-precos-btl96\/ alt=&quot;Nueva amenaza de huelga podr\u00eda reavivar recuerdos amargos&quot;), cuando el pa\u00eds experiment\u00f3 escasez y aumentos abruptos de precios.<\/p>\n<p>Estos paros suelen estar motivados por pol\u00edticas de ajuste del precio del combustible, un tema delicado para los conductores que priorizan sus necesidades econ\u00f3micas por encima de todo. [Principales l\u00edderes niegan la huelga](https:\/\/transportemoderno.com.br\/2025\/12\/02\/principais-liderancas-negam-greve-de-caminhoneiros-no-proximo-dia-4-de-dezembro\/ alt=\u201dPrincipales l\u00edderes niegan la huelga de camioneros\u201d), pero la movilizaci\u00f3n es inevitable a medida que se acerca la fecha, con una mayor presi\u00f3n sobre el sector del transporte por carretera.<\/p>\n<h2>Impacto de la huelga en el precio promedio de la gasolina<\/h2>\n<p>El impacto de la huelga de los camioneros en el precio promedio de la gasolina ha sido una preocupaci\u00f3n creciente en Brasil.<\/p>\n<p>Actualmente el costo de un litro de gasolina es... <strong>R$ 6.38<\/strong>Sin embargo, las proyecciones indican que este valor podr\u00eda superar... <strong>R$ 10.00<\/strong> en caso de que la huelga contin\u00fae.<\/p>\n<p>Esto se debe en parte al aumento de los precios del combustible, como ya se ha comentado en... <a href=\"https:\/\/www.radiosantacruzfmg.com.br\/acontece\/noticia\/76733\" alt=\"Aumento do diesel no Brasil\">Noticias sobre los ajustes del precio del di\u00e9sel<\/a>.<\/p>\n<p>El alza de los precios de los combustibles impacta severamente a los consumidores, a las empresas de transporte y a la inflaci\u00f3n, encareciendo el transporte, lo que afecta el precio final de los productos y, en consecuencia, aumenta la inflaci\u00f3n.<\/p>\n<h2>Motivaciones de los camioneros: Condiciones laborales e ICMS (Impuesto sobre la Circulaci\u00f3n de Bienes y Servicios)<\/h2>\n<p>La tensi\u00f3n entre <strong>conductores de camiones<\/strong> Y el gobierno aumenta el aumento debido a diversas circunstancias que afectan directamente la vida cotidiana de quienes est\u00e1n en esta categor\u00eda.<\/p>\n<p>Las complicadas condiciones de trabajo y el aumento de <a href=\"https:\/\/www.camara.leg.br\/noticias\/529808-especialistas-temem-greve-de-caminhoneiros-em-protesto-ao-aumento-do-diesel\" alt=\"Legisla\u00e7\u00e3o sobre ICMS\">ICMS<\/a> Generan descontento y protestas.<\/p>\n<p>En algunos casos, los conductores de camiones se enfrentan a una realidad en la que las entregas se vuelven econ\u00f3micamente inviables.<\/p>\n<ul>\n<li><strong>Falta de puntos de apoyo<\/strong>En muchos tramos de carretera faltan lugares donde los conductores puedan descansar y comer adecuadamente.<\/li>\n<li><strong>Infraestructura deficiente<\/strong>Los baches y la falta de mantenimiento en las carreteras hacen que viajar sea peligroso.<\/li>\n<li><strong>Costos elevados<\/strong>El aumento del ICMS (impuesto brasile\u00f1o sobre las ventas) pone a\u00fan m\u00e1s presi\u00f3n sobre los m\u00e1rgenes de ganancia.<\/li>\n<\/ul>\n<p>Un camionero expres\u00f3 su frustraci\u00f3n: <\/p>\n<blockquote><p>&quot;No podemos trabajar as\u00ed, los costes siguen aumentando&quot;.<\/p>\n<p>&#8220;<\/p><\/blockquote>\n<p> Este escenario no s\u00f3lo afecta a los profesionales, sino que amenaza... <u>suministro nacional<\/u>, generando un efecto domin\u00f3 sobre la econom\u00eda.<\/p>\n<p>Adem\u00e1s, la divisi\u00f3n dentro de la categor\u00eda respecto a la participaci\u00f3n en el paro refleja preocupaciones sobre la econom\u00eda, como lo advierte <a href=\"https:\/\/opopular.com.br\/economia\/caminhoneiros-protestam-em-rodovia-no-para-por-reduc-o-do-icms-sobre-diesel-1.2343291\" alt=\"Protesto de caminhoneiros no Par\u00e1\">recientes protestas en las carreteras<\/a>.<\/p>\n<p>La compleja situaci\u00f3n exige atenci\u00f3n urgente para evitar que la situaci\u00f3n actual empeore.<\/p>\n<h2>Divisi\u00f3n entre los camioneros: pol\u00edtica y econom\u00eda<\/h2>\n<p>La divisi\u00f3n entre los camioneros en Brasil se ha intensificado debido a los desacuerdos. <strong>pol\u00edticas<\/strong> y los factores econ\u00f3micos involucrados en las discusiones sobre la nueva huelga.<\/p>\n<p>Algunos camioneros se oponen a la huelga, se\u00f1alando que el movimiento ha adquirido un car\u00e1cter m\u00e1s pol\u00edtico. <u>pol\u00edtico<\/u>, aline\u00e1ndose con agendas que no tienen relaci\u00f3n con las demandas hist\u00f3ricas de la categor\u00eda.<\/p>\n<p>Este enfoque pol\u00edtico es visto por algunos como una distracci\u00f3n de los temas centrales, debilitando la unidad del grupo, como se analiza en <a href=\"https:\/\/expressaorondonia.com.br\/chamado-de-greve-nacional-encontra-baixa-adesao-e-gera-divisao-entre-caminhoneiros\/\" alt=\"Discuss\u00e3o sobre a baixa ades\u00e3o \u00e0 greve dos caminhoneiros\">detalles de la baja participaci\u00f3n en la huelga<\/a>.<\/p>\n<p>Adem\u00e1s, existen preocupaciones econ\u00f3micas reales, que van desde el impacto en la ya fr\u00e1gil econom\u00eda nacional hasta el riesgo de que los precios del combustible suban m\u00e1s all\u00e1 de los altos niveles actuales.<\/p>\n<p>Para muchos camioneros, la interrupci\u00f3n de actividades podr\u00eda empeorar la situaci\u00f3n econ\u00f3mica en lugar de aliviar sus presiones financieras.<\/p>\n<p>La falta de consenso disminuye el poder de negociaci\u00f3n con el gobierno, haciendo de las negociaciones una tarea a\u00fan m\u00e1s dif\u00edcil.<\/p>\n<p>En un escenario tan dividido, donde la unidad se ha fragmentado en m\u00faltiples agendas, los camioneros enfrentan desaf\u00edos complejos en la b\u00fasqueda de soluciones que realmente satisfagan sus necesidades, como <a href=\"https:\/\/www.gazetadopovo.com.br\/economia\/racha-entre-caminhoneiros-por-pauta-politica-esvazia-greve-em-todo-o-pais\/\" alt=\"Desafios enfrentados pelos caminhoneiros na busca por solu\u00e7\u00f5es\">Los desaf\u00edos que enfrentan los conductores de camiones<\/a>.<\/p>\n<p>Mantener el foco en las cuestiones esenciales puede ser la clave para recuperar la unidad y la fuerza necesarias para impulsar mejoras reales.<\/p>\n<p><strong>Huelga de camioneros<\/strong> Sigue siendo un tema crucial en el escenario brasile\u00f1o, reflejando las tensiones existentes entre la clase trabajadora y las pol\u00edticas gubernamentales.<\/p>\n<p>Mantenerse al tanto de estos avances es esencial para comprender el futuro del transporte y la econom\u00eda del pa\u00eds.<\/p>","protected":false},"excerpt":{"rendered":"<p>Greve Caminhoneiros \u00e9 o tema central deste artigo, que ir\u00e1 explorar a crescente expectativa por uma nova paralisa\u00e7\u00e3o dos caminhoneiros no Brasil, especialmente ap\u00f3s a recente greve nacional em 4 de dezembro. Vamos analisar como essa situa\u00e7\u00e3o impacta o pre\u00e7o dos combust\u00edveis, com a gasolina podendo ultrapassar R$ 10 por [&hellip;]<\/p>","protected":false},"author":12,"featured_media":1883,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[205],"tags":[1332,1330,1331],"class_list":["post-1885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-greve-caminhoneiros","tag-icms-brasil","tag-preco-gasolina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Expectativa de Nova Greve dos Caminhoneiros Aumenta - Holfik<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/holfik.com\/esp\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expectativa de Nova Greve dos Caminhoneiros Aumenta - Holfik\" \/>\n<meta property=\"og:description\" content=\"Greve Caminhoneiros \u00e9 o tema central deste artigo, que ir\u00e1 explorar a crescente expectativa por uma nova paralisa\u00e7\u00e3o dos caminhoneiros no Brasil, especialmente ap\u00f3s a recente greve nacional em 4 de dezembro. Vamos analisar como essa situa\u00e7\u00e3o impacta o pre\u00e7o dos combust\u00edveis, com a gasolina podendo ultrapassar R$ 10 por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/holfik.com\/esp\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/\" \/>\n<meta property=\"og:site_name\" content=\"Holfik\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-07T20:02:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/12\/1765137717318.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"624\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Davi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Davi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/\"},\"author\":{\"name\":\"Davi\",\"@id\":\"https:\/\/holfik.com\/nb\/#\/schema\/person\/5c63274d844400d16a20c978368aa232\"},\"headline\":\"Expectativa de Nova Greve dos Caminhoneiros Aumenta\",\"datePublished\":\"2025-12-07T20:02:02+00:00\",\"dateModified\":\"2025-12-07T20:02:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/\"},\"wordCount\":927,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/holfik.com\/nb\/#organization\"},\"image\":{\"@id\":\"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/12\/1765137717318.png\",\"keywords\":[\"greve caminhoneiros\",\"ICMS Brasil\",\"pre\u00e7o gasolina\"],\"articleSection\":[\"Economia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/\",\"url\":\"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/\",\"name\":\"Expectativa de Nova Greve dos Caminhoneiros Aumenta - Holfik\",\"isPartOf\":{\"@id\":\"https:\/\/holfik.com\/nb\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/12\/1765137717318.png\",\"datePublished\":\"2025-12-07T20:02:02+00:00\",\"dateModified\":\"2025-12-07T20:02:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/#primaryimage\",\"url\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/12\/1765137717318.png\",\"contentUrl\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/12\/1765137717318.png\",\"width\":1024,\"height\":624,\"caption\":\"undefined\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/holfik.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Expectativa de Nova Greve dos Caminhoneiros Aumenta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/holfik.com\/nb\/#website\",\"url\":\"https:\/\/holfik.com\/nb\/\",\"name\":\"Holfik\",\"description\":\"Site de Not\u00edcias e M\u00eddia\",\"publisher\":{\"@id\":\"https:\/\/holfik.com\/nb\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/holfik.com\/nb\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/holfik.com\/nb\/#organization\",\"name\":\"Holfik\",\"url\":\"https:\/\/holfik.com\/nb\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/holfik.com\/nb\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/download1.png\",\"contentUrl\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/download1.png\",\"width\":150,\"height\":100,\"caption\":\"Holfik\"},\"image\":{\"@id\":\"https:\/\/holfik.com\/nb\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/holfik.com\/nb\/#\/schema\/person\/5c63274d844400d16a20c978368aa232\",\"name\":\"Davi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/holfik.com\/nb\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e1ee68e758cac208b2e5afa99bab2ebc9c971f628c4e810fe37ef98f59af2f71?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e1ee68e758cac208b2e5afa99bab2ebc9c971f628c4e810fe37ef98f59af2f71?s=96&d=mm&r=g\",\"caption\":\"Davi\"},\"url\":\"https:\/\/holfik.com\/esp\/author\/davi\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Expectativa de Nova Greve dos Caminhoneiros Aumenta - Holfik","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/holfik.com\/esp\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/","og_locale":"es_ES","og_type":"article","og_title":"Expectativa de Nova Greve dos Caminhoneiros Aumenta - Holfik","og_description":"Greve Caminhoneiros \u00e9 o tema central deste artigo, que ir\u00e1 explorar a crescente expectativa por uma nova paralisa\u00e7\u00e3o dos caminhoneiros no Brasil, especialmente ap\u00f3s a recente greve nacional em 4 de dezembro. Vamos analisar como essa situa\u00e7\u00e3o impacta o pre\u00e7o dos combust\u00edveis, com a gasolina podendo ultrapassar R$ 10 por [&hellip;]","og_url":"https:\/\/holfik.com\/esp\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/","og_site_name":"Holfik","article_published_time":"2025-12-07T20:02:02+00:00","og_image":[{"width":1024,"height":624,"url":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/12\/1765137717318.png","type":"image\/png"}],"author":"Davi","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Davi","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/#article","isPartOf":{"@id":"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/"},"author":{"name":"Davi","@id":"https:\/\/holfik.com\/nb\/#\/schema\/person\/5c63274d844400d16a20c978368aa232"},"headline":"Expectativa de Nova Greve dos Caminhoneiros Aumenta","datePublished":"2025-12-07T20:02:02+00:00","dateModified":"2025-12-07T20:02:02+00:00","mainEntityOfPage":{"@id":"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/"},"wordCount":927,"commentCount":0,"publisher":{"@id":"https:\/\/holfik.com\/nb\/#organization"},"image":{"@id":"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/#primaryimage"},"thumbnailUrl":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/12\/1765137717318.png","keywords":["greve caminhoneiros","ICMS Brasil","pre\u00e7o gasolina"],"articleSection":["Economia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/","url":"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/","name":"Expectativa de Nova Greve dos Caminhoneiros Aumenta - Holfik","isPartOf":{"@id":"https:\/\/holfik.com\/nb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/#primaryimage"},"image":{"@id":"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/#primaryimage"},"thumbnailUrl":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/12\/1765137717318.png","datePublished":"2025-12-07T20:02:02+00:00","dateModified":"2025-12-07T20:02:02+00:00","breadcrumb":{"@id":"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/#primaryimage","url":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/12\/1765137717318.png","contentUrl":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/12\/1765137717318.png","width":1024,"height":624,"caption":"undefined"},{"@type":"BreadcrumbList","@id":"https:\/\/holfik.com\/sv\/expectativa-de-nova-greve-dos-caminhoneiros-aumenta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/holfik.com\/"},{"@type":"ListItem","position":2,"name":"Expectativa de Nova Greve dos Caminhoneiros Aumenta"}]},{"@type":"WebSite","@id":"https:\/\/holfik.com\/nb\/#website","url":"https:\/\/holfik.com\/nb\/","name":"Holfik","description":"Site de Not\u00edcias e M\u00eddia","publisher":{"@id":"https:\/\/holfik.com\/nb\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/holfik.com\/nb\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/holfik.com\/nb\/#organization","name":"Holfik","url":"https:\/\/holfik.com\/nb\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/holfik.com\/nb\/#\/schema\/logo\/image\/","url":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/download1.png","contentUrl":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/download1.png","width":150,"height":100,"caption":"Holfik"},"image":{"@id":"https:\/\/holfik.com\/nb\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/holfik.com\/nb\/#\/schema\/person\/5c63274d844400d16a20c978368aa232","name":"Davi","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/holfik.com\/nb\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e1ee68e758cac208b2e5afa99bab2ebc9c971f628c4e810fe37ef98f59af2f71?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e1ee68e758cac208b2e5afa99bab2ebc9c971f628c4e810fe37ef98f59af2f71?s=96&d=mm&r=g","caption":"Davi"},"url":"https:\/\/holfik.com\/esp\/author\/davi\/"}]}},"_links":{"self":[{"href":"https:\/\/holfik.com\/esp\/wp-json\/wp\/v2\/posts\/1885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/holfik.com\/esp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/holfik.com\/esp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/holfik.com\/esp\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/holfik.com\/esp\/wp-json\/wp\/v2\/comments?post=1885"}],"version-history":[{"count":0,"href":"https:\/\/holfik.com\/esp\/wp-json\/wp\/v2\/posts\/1885\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/holfik.com\/esp\/wp-json\/wp\/v2\/media\/1883"}],"wp:attachment":[{"href":"https:\/\/holfik.com\/esp\/wp-json\/wp\/v2\/media?parent=1885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/holfik.com\/esp\/wp-json\/wp\/v2\/categories?post=1885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/holfik.com\/esp\/wp-json\/wp\/v2\/tags?post=1885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}