{"id":807,"date":"2025-07-04T10:37:13","date_gmt":"2025-07-04T13:37:13","guid":{"rendered":"https:\/\/holfik.com\/deputado-critica-taxacao-das-lcas-e-lcis\/"},"modified":"2025-07-04T10:37:13","modified_gmt":"2025-07-04T13:37:13","slug":"deputado-critica-taxacao-das-lcas-e-lcis","status":"publish","type":"post","link":"https:\/\/holfik.com\/de\/deputado-critica-taxacao-das-lcas-e-lcis\/","title":{"rendered":"Abgeordneter kritisiert Besteuerung von LCAs und LCIs"},"content":{"rendered":"<p><strong>Der LCA-Besteuerungsvorschlag<\/strong> und Immobilienkreditbriefe (LCIs) durch die Bundesregierung haben in der brasilianischen Wirtschaft heftige Debatten ausgel\u00f6st.<\/p>\n<p>In diesem Artikel untersuchen wir die Kritik von Experten und Parlamentariern an dieser Ma\u00dfnahme und heben die m\u00f6glichen negativen Auswirkungen auf die brasilianische Wirtschaft und Wettbewerbsf\u00e4higkeit hervor.<\/p>\n<p>Dar\u00fcber hinaus werden wir die Bedeutung dieser Akkreditive f\u00fcr die Finanzierung wichtiger Sektoren wie der Agrarindustrie und der Bauwirtschaft er\u00f6rtern und die Notwendigkeit einer \u00dcberpr\u00fcfung der Steuervorteile zur Optimierung der \u00f6ffentlichen Ausgaben und zur Erf\u00fcllung aller Anforderungen des Landes erl\u00e4utern.<\/p>\n<h2>Kritik des Abgeordneten an der Besteuerung von LCAs und LCIs<\/h2>\n<p><p>Der Abgeordnete \u00e4u\u00dferte seinen entschiedenen Einspruch gegen den Vorschlag der Regierung, Agribusiness Credit Letters (LCAs) und Real Estate Credit Letters (LCIs) zu besteuern. <strong>mit der Begr\u00fcndung, dass die Ma\u00dfnahme das Investitionsumfeld in Brasilien schw\u00e4chen w\u00fcrde<\/strong>.<\/p>\n<p>Ihm zufolge sind diese Briefe wichtige Instrumente, um die Finanzierung in wichtigen Sektoren wie dem Hoch- und Tiefbau und der Agrarindustrie zu erleichtern und so ein nachhaltiges Wirtschaftswachstum zu f\u00f6rdern.<\/p>\n<p>Er betont, dass die Besteuerung <strong>droht, die Finanzierungskosten zu erh\u00f6hen<\/strong>, was Investitionen in lebenswichtigen Bereichen verhindert.<\/p>\n<\/p>\n<blockquote><p>\u201eBei der Besteuerung von LCI und LCA <u><strong>Die Regierung greift diejenigen direkt an, die die Wirtschaft antreiben<\/strong><\/u>&#8220;<\/p><\/blockquote>\n<p>Dar\u00fcber hinaus kritisierte der Abgeordnete, dass es im Haushaltskonzept der Regierung an einer angemessenen \u00dcberpr\u00fcfung der Steuervorteile mangele und betonte die dringende Notwendigkeit eines effizienteren Haushalts, um eine \u00dcbertreibung der \u00f6ffentlichen Ausgaben zu vermeiden.<\/p>\n<p>Er argumentierte, dass eine besser formulierte Steuerpolitik den Anforderungen aller Sektoren gerecht werden k\u00f6nne. <strong>ohne die Produktivit\u00e4t zu beeintr\u00e4chtigen<\/strong> des Landes.<\/p>\n<\/p>\n<p>Ausf\u00fchrlichere Informationen finden Sie in der vollst\u00e4ndigen Analyse unter <a href=\"https:\/\/www.cnnbrasil.com.br\/economia\/macroeconomia\/ao-taxar-lci-e-lca-governo-ataca-quem-move-a-economia-diz-deputado\/\" alt=\"An\u00e1lise CNN Brasil\">CNN Brasilien<\/a>.<\/p>\n<\/p>\n<ul>\n<li><strong>Erh\u00f6hte Finanzierungskosten<\/strong><\/li>\n<li><strong>Verringerung der nationalen Wettbewerbsf\u00e4higkeit<\/strong><\/li>\n<li><strong>Verbesserungsbedarf im Steuermanagement<\/strong><\/li>\n<\/ul>\n<h2>Auswirkungen der Besteuerung auf Wettbewerbsf\u00e4higkeit und Produktionst\u00e4tigkeit<\/h2>\n<p>Die Besteuerung von Agrarkreditbriefen (LCAs) und Immobilienkreditbriefen (LCIs) hat erhebliche Auswirkungen auf die brasilianische Wirtschaft, da sie Kredite verteuert und den Zugang zu Finanzierungen in wichtigen Sektoren erschwert.<\/p>\n<p>Dieser Preisanstieg kann zu einem R\u00fcckgang der Investitionen f\u00fchren, die Produktionst\u00e4tigkeit hemmen und das Wirtschaftswachstum behindern.<\/p>\n<p>Dar\u00fcber hinaus gef\u00e4hrdet der durch diese Ma\u00dfnahme verursachte Verlust an Wettbewerbsf\u00e4higkeit die Position Brasiliens auf einem zunehmend anspruchsvollen Weltmarkt.<\/p>\n<h2>Auswirkungen auf die Unternehmenskapitalkosten<\/h2>\n<p>Besteuerung von <u>\u00d6kobilanzen<\/u> Es ist <u>LCIs<\/u> hat direkte Auswirkungen auf die Kapitalkosten brasilianischer Unternehmen, insbesondere im Immobilien- und Agrarsektor.<\/p>\n<p>Wie im Artikel erkl\u00e4rt <a href=\"https:\/\/www1.folha.uol.com.br\/mercado\/2025\/06\/tributacao-de-titulos-como-lci-e-lca-pode-dificultar-credito-para-moradia-e-safra-do-agro-dizem-setores.shtml\" alt=\"Tributa\u00e7\u00e3o e seu impacto no setor imobili\u00e1rio e agro\">Blatt<\/a>warnen Branchenvertreter vor der <strong>Anstieg der Kreditkosten<\/strong>, was durch einen Einkommensteuersatz von 5% noch versch\u00e4rft werden kann.<\/p>\n<p>Dies f\u00fchrt zu geringeren Investitionen und einer m\u00f6glichen Schrumpfung des Arbeitsmarktes.<\/p>\n<p>Marktdaten deuten auf m\u00f6gliche Schwankungen der Zinss\u00e4tze, steigende Spreads und eine Verringerung der Wettbewerbsf\u00e4higkeit hin.<\/p>\n<p>Dies hat zur Folge, dass sich f\u00fcr Unternehmen die Beschaffung von Finanzmitteln schwieriger gestaltet, was ihre Innovations- und Expansionsf\u00e4higkeit beeintr\u00e4chtigen kann.<\/p>\n<p>Als Folge davon, dass in einer bereits fragilen Wirtschaft die <u>Notwendigkeit wirksamer \u00f6ffentlicher Politik<\/u> Es wird noch wichtiger, die negativen Auswirkungen dieser Besteuerung abzumildern.<\/p>\n<h2>Rolle von LCIs und LCAs bei der Finanzierung wichtiger Sektoren<\/h2>\n<p>Zum <strong>LCIs<\/strong> (Immobilienkreditbriefe) und <strong>\u00d6kobilanzen<\/strong> (Agribusiness Credit Letters) entstanden als Finanzinstrumente zur F\u00f6rderung <strong>wesentliche Sektoren<\/strong> der brasilianischen Wirtschaft, wie zum Beispiel <strong>Hoch- und Tiefbau<\/strong> und Agrarindustrie.<\/p>\n<p>Das Hauptziel seiner Gr\u00fcndung bestand darin, die <strong>Finanzierung<\/strong> dieser Sektoren und schafft so ein g\u00fcnstigeres Umfeld f\u00fcr die Beschaffung von Mitteln und die daraus resultierende wirtschaftliche Entwicklung.<\/p>\n<p>Da Privatpersonen von der Einkommensteuer befreit sind, werden Anleger durch wettbewerbsf\u00e4hige und sichere Renditen angezogen, was diese Anleihen sehr beliebt macht.<\/p>\n<p>Die Rolle von LCIs und LCAs bei der Unterst\u00fctzung des Wachstums des Immobilien- und Agrarsektors kann nicht untersch\u00e4tzt werden.<\/p>\n<p>Sie bieten eine effiziente M\u00f6glichkeit, Ressourcen in die Produktion zu lenken, den Kostendruck zu verringern und Projekte von gro\u00dfer wirtschaftlicher Relevanz zu erm\u00f6glichen.<\/p>\n<p>Dar\u00fcber hinaus, indem die <strong>Finanzierung<\/strong> Diese Instrumente sind leichter zug\u00e4nglich und tragen dazu bei, regionale Ungleichheiten zu verringern und die Wettbewerbsf\u00e4higkeit brasilianischer Produkte auf dem internationalen Markt zu steigern.<\/p>\n<p><a href=\"https:\/\/www.infomoney.com.br\/economia\/setor-da-construcao-diz-que-taxacao-de-lci-pode-aumentar-custo-da-casa-propria\/\" alt=\"Sector da constru\u00e7\u00e3o\">Der Bausektor behauptet, dass die Besteuerung von LCIs die Kosten des Wohneigentums erh\u00f6ht<\/a>, was sich direkt auf die Kaufkraft der Bev\u00f6lkerung auswirkt.<\/p>\n<p>Diese Verbindung zwischen LCIs\/LCAs und der Wirtschaft wird noch deutlicher, wenn man die gro\u00dfe Bandbreite an Arbeitspl\u00e4tzen ber\u00fccksichtigt, die durch diese Finanzmechanismen geschaffen werden.<\/p>\n<blockquote><p>Investitionen in LCIs und LCAs gelten als Br\u00fccke zwischen privatem Kapital und der Nachfrage nach nachhaltigem Wachstum<\/p><\/blockquote>\n<p>, betont ein Branchenexperte die gesellschaftliche und wirtschaftliche Bedeutung dieser Titel.<\/p>\n<h2>Vorschl\u00e4ge f\u00fcr eine effizientere Fiskalpolitik<\/h2>\n<p>Der Abgeordnete kritisierte die aktuelle Finanzpolitik und wies auf die M\u00e4ngel hin, die das Wachstum der brasilianischen Wirtschaft sch\u00e4digen.<\/p>\n<p>Er weist darauf hin, dass der Vorschlag, Agribusiness Credit Letters (LCAs) und Real Estate Credit Letters (LCIs) zu besteuern, die Wettbewerbsf\u00e4higkeit wichtiger Sektoren wie des Hoch- und Tiefbaus und der Agrarindustrie gef\u00e4hrde.<\/p>\n<p><strong>Diese Besteuerung kann die produktive T\u00e4tigkeit schw\u00e4chen<\/strong>, was von wesentlichen Investitionen abschreckt.<\/p>\n<p><u><strong>Vorschl\u00e4ge zur Verbesserung der Finanzpolitik<\/strong><\/u><\/p>\n<p>Der Abgeordnete schl\u00e4gt eine \u00dcberpr\u00fcfung der Steuerverg\u00fcnstigungen vor. Er h\u00e4lt es f\u00fcr unabdingbar, einen Haushalt zu entwickeln, der den Bed\u00fcrfnissen aller Sektoren wirksam Rechnung tr\u00e4gt, ohne einen ungez\u00fcgelten Anstieg der Ausgaben zu f\u00f6rdern.<\/p>\n<ol>\n<li>F\u00fchren Sie eine gr\u00fcndliche Bewertung der bestehenden Steuervorteile durch und stellen Sie die Wirksamkeit sicher. <u>Transparenz<\/u>Mehr dazu unter <a href=\"https:\/\/www.camara.leg.br\/noticias\/1175215-deputados-aprovam-urgencia-para-projeto-sobre-avaliacao-de-incentivos-fiscais\" alt=\"Avalia\u00e7\u00e3o de incentivos fiscais pela C\u00e2mara dos Deputados\">Beurteilung der Steueranreize durch die Abgeordnetenkammer<\/a>.<\/li>\n<li>Implementierung klarer und technischer Regeln f\u00fcr die Gew\u00e4hrung von Leistungen, <strong>Minimierung wirtschaftlicher Verzerrungen<\/strong>Weitere Einzelheiten finden Sie unter <a href=\"https:\/\/www.moneytimes.com.br\/camara-aprova-urgencia-de-projeto-que-cria-regras-para-concessao\" alt=\"Regras para concess\u00e3o de benef\u00edcios tribut\u00e1rios\">Regeln f\u00fcr die Gew\u00e4hrung von Steuervorteilen<\/a>.<\/li>\n<li>\u00dcberpr\u00fcfung der \u00f6ffentlichen Ausgaben, wobei Investitionen in wesentliche Infrastruktur und strategische Sektoren, wie erw\u00e4hnt, Priorit\u00e4t haben sollten <a href=\"https:\/\/g1.globo.com\/politica\/noticia\/2025\/07\/02\/camara-aprova-urgencia-para-projeto-que-reavalia-concessao-de-incentivos-fiscais.ghtml\" alt=\"Reavalia\u00e7\u00e3o dos incentivos fiscais pela C\u00e2mara\">Neubewertung der Steuerf\u00f6rderung durch die Kammer<\/a>.<\/li>\n<li><u><strong>St\u00e4rkung \u00f6ffentlich-privater Partnerschaften<\/strong><\/u> um Ressourcen zu optimieren und die Investitionseffizienz zu steigern.<\/li>\n<\/ol>\n<p>Dies gleicht den Haushalt aus, ohne wichtige Produktionssektoren zu beeintr\u00e4chtigen, und f\u00f6rdert eine <u>nachhaltige wirtschaftliche Entwicklung<\/u>.<\/p>\n<p><strong>Die Diskussion \u00fcber die Besteuerung von \u00d6kobilanzen<\/strong> und LCIs sind f\u00fcr die Zukunft der brasilianischen Wirtschaft von entscheidender Bedeutung.<\/p>\n<p>Der Erhalt dieser Finanzinstrumente ist von entscheidender Bedeutung, um Brasiliens nachhaltiges Wachstum und seine Wettbewerbsf\u00e4higkeit auf dem Weltmarkt zu gew\u00e4hrleisten.<\/p>","protected":false},"excerpt":{"rendered":"<p>A proposta de taxa\u00e7\u00e3o LCAs e Letras de Cr\u00e9dito Imobili\u00e1rio (LCIs) pelo governo federal tem gerado intensos debates no cen\u00e1rio econ\u00f4mico brasileiro. Neste artigo, vamos explorar as cr\u00edticas feitas por especialistas e parlamentares diante dessa medida, destacando os poss\u00edveis impactos negativos sobre a economia e a competitividade do Brasil. Al\u00e9m [&hellip;]<\/p>","protected":false},"author":12,"featured_media":806,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[205],"tags":[275,273,274],"class_list":["post-807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-competitividade","tag-economia","tag-tributacao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Deputado Critica Taxa\u00e7\u00e3o das LCAs e LCIs - Holfik<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/holfik.com\/de\/deputado-critica-taxacao-das-lcas-e-lcis\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deputado Critica Taxa\u00e7\u00e3o das LCAs e LCIs - Holfik\" \/>\n<meta property=\"og:description\" content=\"A proposta de taxa\u00e7\u00e3o LCAs e Letras de Cr\u00e9dito Imobili\u00e1rio (LCIs) pelo governo federal tem gerado intensos debates no cen\u00e1rio econ\u00f4mico brasileiro. Neste artigo, vamos explorar as cr\u00edticas feitas por especialistas e parlamentares diante dessa medida, destacando os poss\u00edveis impactos negativos sobre a economia e a competitividade do Brasil. Al\u00e9m [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/holfik.com\/de\/deputado-critica-taxacao-das-lcas-e-lcis\/\" \/>\n<meta property=\"og:site_name\" content=\"Holfik\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-04T13:37:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/req-5nifyVyq59lbzCT6S35Z7-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"624\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Davi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Davi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/\"},\"author\":{\"name\":\"Davi\",\"@id\":\"https:\/\/holfik.com\/nb\/#\/schema\/person\/5c63274d844400d16a20c978368aa232\"},\"headline\":\"Deputado Critica Taxa\u00e7\u00e3o das LCAs e LCIs\",\"datePublished\":\"2025-07-04T13:37:13+00:00\",\"dateModified\":\"2025-07-04T13:37:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/\"},\"wordCount\":1104,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/holfik.com\/nb\/#organization\"},\"image\":{\"@id\":\"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/req-5nifyVyq59lbzCT6S35Z7-1.png\",\"keywords\":[\"competitividade\",\"economia\",\"tributa\u00e7\u00e3o\"],\"articleSection\":[\"Economia\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/\",\"url\":\"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/\",\"name\":\"Deputado Critica Taxa\u00e7\u00e3o das LCAs e LCIs - Holfik\",\"isPartOf\":{\"@id\":\"https:\/\/holfik.com\/nb\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/req-5nifyVyq59lbzCT6S35Z7-1.png\",\"datePublished\":\"2025-07-04T13:37:13+00:00\",\"dateModified\":\"2025-07-04T13:37:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/#primaryimage\",\"url\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/req-5nifyVyq59lbzCT6S35Z7-1.png\",\"contentUrl\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/req-5nifyVyq59lbzCT6S35Z7-1.png\",\"width\":1024,\"height\":624,\"caption\":\"Deputado fala sobre taxa\u00e7\u00e3o das Letras de Cr\u00e9dito do Agroneg\u00f3cio e Imobili\u00e1rio, discutindo consequ\u00eancias para a economia.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/holfik.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deputado Critica Taxa\u00e7\u00e3o das LCAs e LCIs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/holfik.com\/nb\/#website\",\"url\":\"https:\/\/holfik.com\/nb\/\",\"name\":\"Holfik\",\"description\":\"Site de Not\u00edcias e M\u00eddia\",\"publisher\":{\"@id\":\"https:\/\/holfik.com\/nb\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/holfik.com\/nb\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/holfik.com\/nb\/#organization\",\"name\":\"Holfik\",\"url\":\"https:\/\/holfik.com\/nb\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/holfik.com\/nb\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/download1.png\",\"contentUrl\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/download1.png\",\"width\":150,\"height\":100,\"caption\":\"Holfik\"},\"image\":{\"@id\":\"https:\/\/holfik.com\/nb\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/holfik.com\/nb\/#\/schema\/person\/5c63274d844400d16a20c978368aa232\",\"name\":\"Davi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/holfik.com\/nb\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e1ee68e758cac208b2e5afa99bab2ebc9c971f628c4e810fe37ef98f59af2f71?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e1ee68e758cac208b2e5afa99bab2ebc9c971f628c4e810fe37ef98f59af2f71?s=96&d=mm&r=g\",\"caption\":\"Davi\"},\"url\":\"https:\/\/holfik.com\/de\/author\/davi\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deputado Critica Taxa\u00e7\u00e3o das LCAs e LCIs - Holfik","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/holfik.com\/de\/deputado-critica-taxacao-das-lcas-e-lcis\/","og_locale":"de_DE","og_type":"article","og_title":"Deputado Critica Taxa\u00e7\u00e3o das LCAs e LCIs - Holfik","og_description":"A proposta de taxa\u00e7\u00e3o LCAs e Letras de Cr\u00e9dito Imobili\u00e1rio (LCIs) pelo governo federal tem gerado intensos debates no cen\u00e1rio econ\u00f4mico brasileiro. Neste artigo, vamos explorar as cr\u00edticas feitas por especialistas e parlamentares diante dessa medida, destacando os poss\u00edveis impactos negativos sobre a economia e a competitividade do Brasil. Al\u00e9m [&hellip;]","og_url":"https:\/\/holfik.com\/de\/deputado-critica-taxacao-das-lcas-e-lcis\/","og_site_name":"Holfik","article_published_time":"2025-07-04T13:37:13+00:00","og_image":[{"width":1024,"height":624,"url":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/req-5nifyVyq59lbzCT6S35Z7-1.png","type":"image\/png"}],"author":"Davi","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"Davi","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/#article","isPartOf":{"@id":"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/"},"author":{"name":"Davi","@id":"https:\/\/holfik.com\/nb\/#\/schema\/person\/5c63274d844400d16a20c978368aa232"},"headline":"Deputado Critica Taxa\u00e7\u00e3o das LCAs e LCIs","datePublished":"2025-07-04T13:37:13+00:00","dateModified":"2025-07-04T13:37:13+00:00","mainEntityOfPage":{"@id":"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/"},"wordCount":1104,"commentCount":0,"publisher":{"@id":"https:\/\/holfik.com\/nb\/#organization"},"image":{"@id":"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/#primaryimage"},"thumbnailUrl":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/req-5nifyVyq59lbzCT6S35Z7-1.png","keywords":["competitividade","economia","tributa\u00e7\u00e3o"],"articleSection":["Economia"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/","url":"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/","name":"Deputado Critica Taxa\u00e7\u00e3o das LCAs e LCIs - Holfik","isPartOf":{"@id":"https:\/\/holfik.com\/nb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/#primaryimage"},"image":{"@id":"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/#primaryimage"},"thumbnailUrl":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/req-5nifyVyq59lbzCT6S35Z7-1.png","datePublished":"2025-07-04T13:37:13+00:00","dateModified":"2025-07-04T13:37:13+00:00","breadcrumb":{"@id":"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/#primaryimage","url":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/req-5nifyVyq59lbzCT6S35Z7-1.png","contentUrl":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/req-5nifyVyq59lbzCT6S35Z7-1.png","width":1024,"height":624,"caption":"Deputado fala sobre taxa\u00e7\u00e3o das Letras de Cr\u00e9dito do Agroneg\u00f3cio e Imobili\u00e1rio, discutindo consequ\u00eancias para a economia."},{"@type":"BreadcrumbList","@id":"https:\/\/holfik.com\/en\/deputado-critica-taxacao-das-lcas-e-lcis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/holfik.com\/"},{"@type":"ListItem","position":2,"name":"Deputado Critica Taxa\u00e7\u00e3o das LCAs e LCIs"}]},{"@type":"WebSite","@id":"https:\/\/holfik.com\/nb\/#website","url":"https:\/\/holfik.com\/nb\/","name":"Holfik","description":"Site de Not\u00edcias e M\u00eddia","publisher":{"@id":"https:\/\/holfik.com\/nb\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/holfik.com\/nb\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/holfik.com\/nb\/#organization","name":"Holfik","url":"https:\/\/holfik.com\/nb\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/holfik.com\/nb\/#\/schema\/logo\/image\/","url":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/download1.png","contentUrl":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/download1.png","width":150,"height":100,"caption":"Holfik"},"image":{"@id":"https:\/\/holfik.com\/nb\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/holfik.com\/nb\/#\/schema\/person\/5c63274d844400d16a20c978368aa232","name":"Davi","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/holfik.com\/nb\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e1ee68e758cac208b2e5afa99bab2ebc9c971f628c4e810fe37ef98f59af2f71?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e1ee68e758cac208b2e5afa99bab2ebc9c971f628c4e810fe37ef98f59af2f71?s=96&d=mm&r=g","caption":"Davi"},"url":"https:\/\/holfik.com\/de\/author\/davi\/"}]}},"_links":{"self":[{"href":"https:\/\/holfik.com\/de\/wp-json\/wp\/v2\/posts\/807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/holfik.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/holfik.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/holfik.com\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/holfik.com\/de\/wp-json\/wp\/v2\/comments?post=807"}],"version-history":[{"count":0,"href":"https:\/\/holfik.com\/de\/wp-json\/wp\/v2\/posts\/807\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/holfik.com\/de\/wp-json\/wp\/v2\/media\/806"}],"wp:attachment":[{"href":"https:\/\/holfik.com\/de\/wp-json\/wp\/v2\/media?parent=807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/holfik.com\/de\/wp-json\/wp\/v2\/categories?post=807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/holfik.com\/de\/wp-json\/wp\/v2\/tags?post=807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}