{"id":1028,"date":"2025-07-30T17:04:13","date_gmt":"2025-07-30T20:04:13","guid":{"rendered":"https:\/\/holfik.com\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/"},"modified":"2025-07-30T17:04:13","modified_gmt":"2025-07-30T20:04:13","slug":"tarifas-de-50-sobre-produtos-exportados-do-brasil","status":"publish","type":"post","link":"https:\/\/holfik.com\/de\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/","title":{"rendered":"50% Z\u00f6lle auf aus Brasilien exportierte Produkte"},"content":{"rendered":"<p><strong>Exportz\u00f6lle<\/strong> waren ein zentrales Thema in den Wirtschaftsgespr\u00e4chen zwischen Brasilien und den Vereinigten Staaten.<\/p>\n<p>In diesem Artikel analysieren wir das j\u00fcngste Dekret, das Z\u00f6lle 50% auf brasilianische Produkte erhebt, und heben die 694 Ausnahmen hervor, wie etwa Orangensaft, Zellulose und Flugzeuge.<\/p>\n<p>Dar\u00fcber hinaus werden wir die zus\u00e4tzlichen Z\u00f6lle 40% auf Kaffee und Fleisch, die Kritik an der brasilianischen Regierung wegen Menschenrechtsverletzungen, N\u00f6tigung von Unternehmen und Zensur politischer Meinungs\u00e4u\u00dferungen sowie die Gr\u00fcnde f\u00fcr diese Z\u00f6lle untersuchen, die den Schutz US-amerikanischer Unternehmen und die nationale Sicherheit betreffen.<\/p>\n<h2>Allgemeiner Tarif von 50 % und seine 694 Ausnahmen<\/h2>\n<p>Das von der US-Regierung unterzeichnete Dekret sieht eine <u><strong>Rate von 50%<\/strong><\/u> auf mehrere aus Brasilien exportierte Produkte, was eine erhebliche Erh\u00f6hung der auf diese Exporte erhobenen Z\u00f6lle bedeutet.<\/p>\n<p>Es ist jedoch wichtig hervorzuheben, dass es <strong>694<\/strong> Ausnahmen innerhalb dieser Ma\u00dfnahme, die strategische Punkte umfasst wie<\/p>\n<ul>\n<li>Orangensaft<\/li>\n<li>Zellulose<\/li>\n<li>Flugzeuge<\/li>\n<\/ul>\n<p>.<\/p>\n<p>Dieser selektive Ansatz zielt darauf ab, <u>Schutz kritischer Sektoren<\/u> Es ist <u>Minimierung der bilateralen wirtschaftlichen Auswirkungen<\/u>.<\/p>\n<p>Dar\u00fcber hinaus entstand dieser Zoll als Reaktion auf Vorw\u00fcrfe von Menschenrechtsverletzungen und der N\u00f6tigung von Unternehmen zur Zensur politischer \u00c4u\u00dferungen durch die brasilianische Regierung, die darauf abzielten, die Interessen von US-Unternehmen zu verteidigen und <u>Wahrung der nationalen Sicherheit<\/u>.<\/p>\n<p>Weitere Informationen zu den Auswirkungen dieser Z\u00f6lle auf brasilianische Exporte finden Sie unter <a href=\"https:\/\/www.cnnbrasil.com.br\/economia\/tarifa-de-50-ameaca-us-40-bi-em-exportacoes-brasileiras-diz-marcos-jank\/\" alt=\"An\u00e1lise do impacto econ\u00f4mico do decreti\">der ausf\u00fchrliche Artikel auf CNN Brasil<\/a>.<\/p>\n<p>Die Einf\u00fchrung dieser Z\u00f6lle stellt Brasilien vor die Herausforderung, seinen internationalen Handel umzulenken und so die wirtschaftlichen Verluste einzud\u00e4mmen.<\/p>\n<h2>Kumulative Z\u00f6lle auf Kaffee und Fleisch<\/h2>\n<p>Die k\u00fcrzlich erfolgte Einf\u00fchrung kumulativer Z\u00f6lle auf Kaffee und Fleisch stellt brasilianische Exporteure vor neue Herausforderungen.<\/p>\n<p>Durch einen zus\u00e4tzlichen Zoll von 401 TP3T, der zum bereits bestehenden Zoll von 101 TP3T hinzukommt, werden die finanziellen Auswirkungen erheblich und erh\u00f6hen die Gesamtkosten f\u00fcr den Export dieser Produkte.<\/p>\n<p>Diese Situation k\u00f6nnte die Wettbewerbsf\u00e4higkeit auf dem internationalen Markt beeintr\u00e4chtigen und den Handelsbeziehungen zwischen Brasilien und den Vereinigten Staaten schaden.<\/p>\n<h2>Berechnung der effektiven Steuerbelastung<\/h2>\n<p>Bei einer Lieferung Kaffee im Wert von 1.000 USD betr\u00e4gt der effektive Zollsatz von 50%, der von der <a href=\"https:\/\/www.cafepoint.com.br\/noticias\/giro-de-noticias\/boletim-carvalhaes-imposicao-de-tarifa-de-50-pelos-eua-prejudica-negocios-de-cafe-238960\/\" alt=\"Boletim Carvalhaes sobre impacto nos neg\u00f3cios de caf\u00e9\">Nordamerikanischer Markt<\/a> wirkt sich direkt auf den Wert des Produkts aus.<\/p>\n<p>Dies bedeutet, dass der zus\u00e4tzlich zu zahlende Betrag 500 USD betr\u00e4gt.<\/p>\n<p>Daher belaufen sich die Gesamtkosten f\u00fcr den Versand auf 1.500 USD.<\/p>\n<p>Dieser Aufwand stellt eine <strong>erhebliche Steuerbelastung<\/strong>, was die Wettbewerbsf\u00e4higkeit des brasilianischen Kaffees auf internationaler Ebene erheblich beeintr\u00e4chtigt. Es ist wichtig, Strategien zu entwickeln, die diese Auswirkungen abmildern und die Nachhaltigkeit der betroffenen Unternehmen gew\u00e4hrleisten.<\/p>\n<h2>Kritik an Menschenrechtsverletzungen<\/h2>\n<p>Das fragliche Dekret unterstreicht die ernsten Bedenken der brasilianischen Regierung hinsichtlich der Vorw\u00fcrfe von <u><strong>Menschenrechtsverletzungen<\/strong><\/u>, in der Praktiken erw\u00e4hnt werden, die die Integrit\u00e4t von Unternehmen und Einzelpersonen gef\u00e4hrden.<\/p>\n<p>Zu diesen Ma\u00dfnahmen geh\u00f6ren die angeblichen <strong>Zwang von Unternehmen<\/strong> um politische Meinungs\u00e4u\u00dferungen zu unterdr\u00fccken, eine Praxis, die die Meinungsfreiheit und die Autonomie von Unternehmen bedroht.<\/p>\n<p>Diese Situation wird als ein Umfeld beschrieben, in dem die Regierung <a href='https:\/\/reporterbrasil.org.br\/2018\/12\/decreto-do-governo-federal-fragiliza-o-cumprimento-dos-direitos-humanos-por-empresas\/' alt='Novo decreto pode fragilizar cumprimento dos direitos humanos'>schw\u00e4cht die Einhaltung der Menschenrechte<\/a>Dadurch entsteht Druck, der Organisationen oft dazu zwingt, gegen ihren Willen restriktive Ma\u00dfnahmen zu ergreifen.<\/p>\n<p>Das Dekret legt nahe, dass andere L\u00e4nder als Reaktion auf diese Praktiken Z\u00f6lle erheben, da derartige Verst\u00f6\u00dfe nicht nur amerikanischen Unternehmen schaden, sondern auch die nationale Sicherheit der USA bedrohen.<\/p>\n<p>Daher wird die Erhebung von Z\u00f6llen als legitime und notwendige Reaktion dargestellt, um diesen Verst\u00f6\u00dfen entgegenzutreten und wirtschaftliche und sicherheitspolitische Interessen zu sch\u00fctzen.<\/p>\n<h2>Rechtfertigungen im Zusammenhang mit der nationalen Sicherheit der USA<\/h2>\n<p>Offizielle Begr\u00fcndungen f\u00fcr die Einf\u00fchrung hoher Z\u00f6lle auf brasilianische Produkte zeigen erhebliche Bedenken hinsichtlich <u><strong>nationale Sicherheit<\/strong><\/u> der Vereinigten Staaten.<\/p>\n<p>Das Dokument erw\u00e4hnt, dass Praktiken und Ma\u00dfnahmen der brasilianischen Regierung <strong>strategische Interessen gef\u00e4hrden<\/strong> aus den USA, insbesondere unter Berufung auf <strong>Amtsmissbrauch<\/strong> Es ist <strong>Einsch\u00fcchterung politischer Gegner<\/strong>.<\/p>\n<p>Diese Praktiken werden als direkte Bedrohung der politischen und wirtschaftlichen Stabilit\u00e4t der Vereinigten Staaten angesehen und rechtfertigen strengere Ma\u00dfnahmen in der Handelspolitik.<\/p>\n<p>Brasiliens Ma\u00dfnahmen beschr\u00e4nken sich jedoch nicht nur auf innenpolitische Probleme. Es wird auch behauptet, dass das Land Unternehmen dazu zwingt, politische \u00c4u\u00dferungen zu zensieren, was die Spannungen auf der internationalen B\u00fchne versch\u00e4rft.<\/p>\n<p>Die US-Regierung argumentiert bei der Ausarbeitung dieser Z\u00f6lle, dass es <u><strong>Verteidigung seiner Souver\u00e4nit\u00e4t<\/strong><\/u> und den Wirtschaftsbereich vor jeglichen negativen Einfl\u00fcssen von au\u00dfen zu sch\u00fctzen.<\/p>\n<p>Weitere Einzelheiten finden Sie auf der Website <a href=\"https:\/\/www.dw.com\/pt-br\/eua-senadores-veem-abuso-de-poder-em-sobretaxa-ao-brasil\/a-73419651\" alt=\"Senadores veem abuso de poder contra o Brasil\">DW zum Machtmissbrauch bei Z\u00f6llen<\/a>.<\/p>\n<p><strong>Zusamenfassend<\/strong>Die von der US-Regierung verh\u00e4ngten Z\u00f6lle spiegeln eine komplexe Schnittstelle zwischen Wirtschaft und Politik wider und werfen Fragen zu Menschenrechten und bilateralen Beziehungen auf.<\/p>\n<p>Die Situation erfordert Aufmerksamkeit und \u00dcberlegungen hinsichtlich der Auswirkungen auf die Beziehungen zwischen den beiden L\u00e4ndern.<\/p>","protected":false},"excerpt":{"rendered":"<p>Tarifas Exportados t\u00eam sido um tema central nas discuss\u00f5es econ\u00f4micas entre Brasil e Estados Unidos. Neste artigo, analisaremos o recente decreto que imp\u00f5e tarifas de 50% sobre produtos brasileiros, destacando as 694 exce\u00e7\u00f5es, como suco de laranja, celulose e avi\u00f5es. Al\u00e9m disso, vamos explorar a tarifa adicional de 40% sobre [&hellip;]<\/p>","protected":false},"author":12,"featured_media":1027,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[205],"tags":[260,509,389],"class_list":["post-1028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-brasil","tag-exportacao","tag-tarifas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tarifas de 50% Sobre Produtos Exportados do Brasil - Holfik<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/holfik.com\/de\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tarifas de 50% Sobre Produtos Exportados do Brasil - Holfik\" \/>\n<meta property=\"og:description\" content=\"Tarifas Exportados t\u00eam sido um tema central nas discuss\u00f5es econ\u00f4micas entre Brasil e Estados Unidos. Neste artigo, analisaremos o recente decreto que imp\u00f5e tarifas de 50% sobre produtos brasileiros, destacando as 694 exce\u00e7\u00f5es, como suco de laranja, celulose e avi\u00f5es. Al\u00e9m disso, vamos explorar a tarifa adicional de 40% sobre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/holfik.com\/de\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/\" \/>\n<meta property=\"og:site_name\" content=\"Holfik\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-30T20:04:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/1753905848151.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"624\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Davi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Davi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/\"},\"author\":{\"name\":\"Davi\",\"@id\":\"https:\/\/holfik.com\/nb\/#\/schema\/person\/5c63274d844400d16a20c978368aa232\"},\"headline\":\"Tarifas de 50% Sobre Produtos Exportados do Brasil\",\"datePublished\":\"2025-07-30T20:04:13+00:00\",\"dateModified\":\"2025-07-30T20:04:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/\"},\"wordCount\":840,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/holfik.com\/nb\/#organization\"},\"image\":{\"@id\":\"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/1753905848151.png\",\"keywords\":[\"Brasil\",\"exporta\u00e7\u00e3o\",\"tarifas\"],\"articleSection\":[\"Economia\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/\",\"url\":\"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/\",\"name\":\"Tarifas de 50% Sobre Produtos Exportados do Brasil - Holfik\",\"isPartOf\":{\"@id\":\"https:\/\/holfik.com\/nb\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/1753905848151.png\",\"datePublished\":\"2025-07-30T20:04:13+00:00\",\"dateModified\":\"2025-07-30T20:04:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/#primaryimage\",\"url\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/1753905848151.png\",\"contentUrl\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/1753905848151.png\",\"width\":1024,\"height\":624,\"caption\":\"undefined\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/holfik.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tarifas de 50% Sobre Produtos Exportados do Brasil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/holfik.com\/nb\/#website\",\"url\":\"https:\/\/holfik.com\/nb\/\",\"name\":\"Holfik\",\"description\":\"Site de Not\u00edcias e M\u00eddia\",\"publisher\":{\"@id\":\"https:\/\/holfik.com\/nb\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/holfik.com\/nb\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/holfik.com\/nb\/#organization\",\"name\":\"Holfik\",\"url\":\"https:\/\/holfik.com\/nb\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/holfik.com\/nb\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/download1.png\",\"contentUrl\":\"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/download1.png\",\"width\":150,\"height\":100,\"caption\":\"Holfik\"},\"image\":{\"@id\":\"https:\/\/holfik.com\/nb\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/holfik.com\/nb\/#\/schema\/person\/5c63274d844400d16a20c978368aa232\",\"name\":\"Davi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/holfik.com\/nb\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e1ee68e758cac208b2e5afa99bab2ebc9c971f628c4e810fe37ef98f59af2f71?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e1ee68e758cac208b2e5afa99bab2ebc9c971f628c4e810fe37ef98f59af2f71?s=96&d=mm&r=g\",\"caption\":\"Davi\"},\"url\":\"https:\/\/holfik.com\/de\/author\/davi\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tarifas de 50% Sobre Produtos Exportados do Brasil - Holfik","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/holfik.com\/de\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/","og_locale":"de_DE","og_type":"article","og_title":"Tarifas de 50% Sobre Produtos Exportados do Brasil - Holfik","og_description":"Tarifas Exportados t\u00eam sido um tema central nas discuss\u00f5es econ\u00f4micas entre Brasil e Estados Unidos. Neste artigo, analisaremos o recente decreto que imp\u00f5e tarifas de 50% sobre produtos brasileiros, destacando as 694 exce\u00e7\u00f5es, como suco de laranja, celulose e avi\u00f5es. Al\u00e9m disso, vamos explorar a tarifa adicional de 40% sobre [&hellip;]","og_url":"https:\/\/holfik.com\/de\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/","og_site_name":"Holfik","article_published_time":"2025-07-30T20:04:13+00:00","og_image":[{"width":1024,"height":624,"url":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/1753905848151.png","type":"image\/png"}],"author":"Davi","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"Davi","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/#article","isPartOf":{"@id":"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/"},"author":{"name":"Davi","@id":"https:\/\/holfik.com\/nb\/#\/schema\/person\/5c63274d844400d16a20c978368aa232"},"headline":"Tarifas de 50% Sobre Produtos Exportados do Brasil","datePublished":"2025-07-30T20:04:13+00:00","dateModified":"2025-07-30T20:04:13+00:00","mainEntityOfPage":{"@id":"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/"},"wordCount":840,"commentCount":0,"publisher":{"@id":"https:\/\/holfik.com\/nb\/#organization"},"image":{"@id":"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/#primaryimage"},"thumbnailUrl":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/1753905848151.png","keywords":["Brasil","exporta\u00e7\u00e3o","tarifas"],"articleSection":["Economia"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/","url":"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/","name":"Tarifas de 50% Sobre Produtos Exportados do Brasil - Holfik","isPartOf":{"@id":"https:\/\/holfik.com\/nb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/#primaryimage"},"image":{"@id":"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/#primaryimage"},"thumbnailUrl":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/1753905848151.png","datePublished":"2025-07-30T20:04:13+00:00","dateModified":"2025-07-30T20:04:13+00:00","breadcrumb":{"@id":"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/#primaryimage","url":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/1753905848151.png","contentUrl":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/1753905848151.png","width":1024,"height":624,"caption":"undefined"},{"@type":"BreadcrumbList","@id":"https:\/\/holfik.com\/nl\/tarifas-de-50-sobre-produtos-exportados-do-brasil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/holfik.com\/"},{"@type":"ListItem","position":2,"name":"Tarifas de 50% Sobre Produtos Exportados do Brasil"}]},{"@type":"WebSite","@id":"https:\/\/holfik.com\/nb\/#website","url":"https:\/\/holfik.com\/nb\/","name":"Holfik","description":"Site de Not\u00edcias e M\u00eddia","publisher":{"@id":"https:\/\/holfik.com\/nb\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/holfik.com\/nb\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/holfik.com\/nb\/#organization","name":"Holfik","url":"https:\/\/holfik.com\/nb\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/holfik.com\/nb\/#\/schema\/logo\/image\/","url":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/download1.png","contentUrl":"https:\/\/holfik.com\/wp-content\/uploads\/2025\/07\/download1.png","width":150,"height":100,"caption":"Holfik"},"image":{"@id":"https:\/\/holfik.com\/nb\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/holfik.com\/nb\/#\/schema\/person\/5c63274d844400d16a20c978368aa232","name":"Davi","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/holfik.com\/nb\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e1ee68e758cac208b2e5afa99bab2ebc9c971f628c4e810fe37ef98f59af2f71?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e1ee68e758cac208b2e5afa99bab2ebc9c971f628c4e810fe37ef98f59af2f71?s=96&d=mm&r=g","caption":"Davi"},"url":"https:\/\/holfik.com\/de\/author\/davi\/"}]}},"_links":{"self":[{"href":"https:\/\/holfik.com\/de\/wp-json\/wp\/v2\/posts\/1028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/holfik.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/holfik.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/holfik.com\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/holfik.com\/de\/wp-json\/wp\/v2\/comments?post=1028"}],"version-history":[{"count":0,"href":"https:\/\/holfik.com\/de\/wp-json\/wp\/v2\/posts\/1028\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/holfik.com\/de\/wp-json\/wp\/v2\/media\/1027"}],"wp:attachment":[{"href":"https:\/\/holfik.com\/de\/wp-json\/wp\/v2\/media?parent=1028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/holfik.com\/de\/wp-json\/wp\/v2\/categories?post=1028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/holfik.com\/de\/wp-json\/wp\/v2\/tags?post=1028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}